{"id":23454,"date":"2022-05-19T20:57:44","date_gmt":"2022-05-20T00:57:44","guid":{"rendered":"https:\/\/www.present.ca\/?page_id=23454"},"modified":"2024-01-03T15:44:26","modified_gmt":"2024-01-03T20:44:26","slug":"un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication","status":"publish","type":"page","link":"https:\/\/www.present.ca\/fr\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\/","title":{"rendered":"Un crypto mining squattait les ressources TI d\u2019une entreprise qu\u00e9b\u00e9coise de fabrication"},"content":{"rendered":"<p>[vc_row][vc_column]<div id=\"ultimate-heading-32956a5744c873401\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-32956a5744c873401 uvc-8192 cursive\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-32956a5744c873401 h2'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h2 style=\"font-weight:normal;\">Industrie: Fabrication<\/h2><\/div><div class=\"uvc-sub-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-32956a5744c873401 .uvc-sub-heading '  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;\"><\/p>\n<h4>Un crypto mining squattait les ressources TI d\u2019une entreprise qu\u00e9b\u00e9coise de fabrication<\/h4>\n<p><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/3&Prime;][vc_column_text]<strong>Situation : <\/strong><\/p>\n<ul>\n<li>L\u2019entreprise se dote de la s\u00e9curit\u00e9 g\u00e9r\u00e9e de Present.<\/li>\n<li>Nous commen\u00e7ons\u00a0l\u2019installation de nos outils de protection et de surveillance.<\/li>\n<li>Imm\u00e9diatement nous d\u00e9celons des activit\u00e9s illicites sur le r\u00e9seau.<\/li>\n<li>En investiguant, nous d\u00e9couvrons un crypto miner.<\/li>\n<li>Le cryto miner est du code qui utilise vos ressources TI afin de calculer les algorithmes de cryptomonnaie.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;][vc_column_text]<strong>Solution:<\/strong><\/p>\n<ul>\n<li>Nous avons isol\u00e9 et \u00e9limin\u00e9 l\u2019intrus des serveurs et avons nettoy\u00e9 le tout de a \u00e0 z.<\/li>\n<li>Nous avons ensuite continu\u00e9 l\u2019installation sur tout le reste de l\u2019environnement.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;][vc_column_text]<strong>B\u00e9n\u00e9fices<\/strong>:<\/p>\n<ul>\n<li>Le client est compl\u00e8tement prot\u00e9ger et a la paix d\u2019esprit que la s\u00e9curit\u00e9 g\u00e9r\u00e9e veille sur ses TI pour qu\u2019ils puissent op\u00e9rer en tout temps.<\/li>\n<li>Le temps r\u00e9ponse des serveurs est beaucoup meilleur car le client b\u00e9n\u00e9ficie de toutes ses ressources syst\u00e8mes..<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row_content\u00a0\u00bb bg_type=\u00a0\u00bbbg_color\u00a0\u00bb el_class=\u00a0\u00bbtilt-pos-3-deg\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1588250693452{padding-top: 25px !important;padding-bottom: 25px !important;}\u00a0\u00bb bg_color_value=\u00a0\u00bb#16a361&Prime;][vc_column]<div id=\"ultimate-heading-22106a5744c873444\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-22106a5744c873444 uvc-1856 \" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-22106a5744c873444 h3'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h3 style=\"font-weight:normal;\">Contactez-nous pour en apprendre d'avantage sur cet \u00e9tude de cas.<\/h3><\/div><\/div>[vc_empty_space]<div class=\" ubtn-ctn-center \"><a class=\"ubtn-link ult-adjust-bottom-margin ubtn-center ubtn-normal \" href=\"\/contact-present\/\" title=\"Contact Present\" ><button type=\"button\" id=\"ubtn-3873\"  class=\"ubtn ult-adjust-bottom-margin ult-responsive ubtn-normal ubtn-no-hover-bg  none  ubtn-center   tooltip-6a5744c873472\"  data-hover=\"#ffffff\" data-border-color=\"#ffffff\" data-bg=\"#ffffff\" data-hover-bg=\"#000000\" data-border-hover=\"#ffffff\" data-shadow-hover=\"\" data-shadow-click=\"none\" data-shadow=\"\" data-shd-shadow=\"\"  data-ultimate-target='#ubtn-3873'  data-responsive-json-new='{\"font-size\":\"desktop:18px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;border-radius:5px;border-width:3px;border-color:#ffffff;border-style:solid;background: #ffffff;color: #16a361;\"><span class=\"ubtn-hover\" style=\"background-color:#000000\"><\/span><span class=\"ubtn-data ubtn-text \" >Parlons-en<\/span><\/button><\/a><\/div>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/3&Prime;][vc_column_text]Situation : L\u2019entreprise se dote de la s\u00e9curit\u00e9 g\u00e9r\u00e9e de Present. Nous commen\u00e7ons\u00a0l\u2019installation de nos outils de protection et de surveillance. Imm\u00e9diatement nous d\u00e9celons des activit\u00e9s illicites sur le r\u00e9seau. En investiguant, nous d\u00e9couvrons un crypto miner. Le cryto miner est du code qui utilise vos ressources TI afin de calculer les algorithmes de [&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":23474,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"class_list":["post-23454","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un crypto mining squattait les ressources TI d\u2019une entreprise qu\u00e9b\u00e9coise de fabrication - Present<\/title>\n<meta name=\"description\" content=\"\u00c9tude de cas sur une entreprise qui avait adopt\u00e9 la solution de s\u00e9curit\u00e9 g\u00e9r\u00e9e de Present, pour constater d\u00e8s l&#039;installation de nos outils de protection et de surveillance, des activit\u00e9s illicites sur le r\u00e9seau. Un crypto-mineur qui utilise vos ressources informatiques afin de calculer des algorithmes de crypto-monnaie a \u00e9t\u00e9 d\u00e9tect\u00e9 puis \u00e9limin\u00e9 du serveur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.present.ca\/fr\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un crypto mining squattait les ressources TI d\u2019une entreprise qu\u00e9b\u00e9coise de fabrication - Present\" \/>\n<meta property=\"og:description\" content=\"\u00c9tude de cas sur une entreprise qui avait adopt\u00e9 la solution de s\u00e9curit\u00e9 g\u00e9r\u00e9e de Present, pour constater d\u00e8s l&#039;installation de nos outils de protection et de surveillance, des activit\u00e9s illicites sur le r\u00e9seau. Un crypto-mineur qui utilise vos ressources informatiques afin de calculer des algorithmes de crypto-monnaie a \u00e9t\u00e9 d\u00e9tect\u00e9 puis \u00e9limin\u00e9 du serveur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.present.ca\/fr\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\/\" \/>\n<meta property=\"og:site_name\" content=\"Present\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-03T20:44:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.present.ca\/wp-content\/uploads\/2022\/05\/Untitled-design-27.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.present.ca\\\/fr\\\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\\\/\",\"url\":\"https:\\\/\\\/www.present.ca\\\/fr\\\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\\\/\",\"name\":\"Un crypto mining squattait les ressources TI d\u2019une entreprise qu\u00e9b\u00e9coise de fabrication - Present\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.present.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.present.ca\\\/fr\\\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.present.ca\\\/fr\\\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.present.ca\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Untitled-design-27.png\",\"datePublished\":\"2022-05-20T00:57:44+00:00\",\"dateModified\":\"2024-01-03T20:44:26+00:00\",\"description\":\"\u00c9tude de cas sur une entreprise qui avait adopt\u00e9 la solution de s\u00e9curit\u00e9 g\u00e9r\u00e9e de Present, pour constater d\u00e8s l'installation de nos outils de protection et de surveillance, des activit\u00e9s illicites sur le r\u00e9seau. Un crypto-mineur qui utilise vos ressources informatiques afin de calculer des algorithmes de crypto-monnaie a \u00e9t\u00e9 d\u00e9tect\u00e9 puis \u00e9limin\u00e9 du serveur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.present.ca\\\/fr\\\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.present.ca\\\/fr\\\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.present.ca\\\/fr\\\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.present.ca\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Untitled-design-27.png\",\"contentUrl\":\"https:\\\/\\\/www.present.ca\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Untitled-design-27.png\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.present.ca\\\/fr\\\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.present.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un crypto mining squattait les ressources TI d\u2019une entreprise qu\u00e9b\u00e9coise de fabrication\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.present.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.present.ca\\\/fr\\\/\",\"name\":\"Present\",\"description\":\"Services G\u00e9r\u00e9s TI, S\u00e9curit\u00e9 G\u00e9r\u00e9e TI et Solutions de Cloud Hybride\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.present.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un crypto mining squattait les ressources TI d\u2019une entreprise qu\u00e9b\u00e9coise de fabrication - Present","description":"\u00c9tude de cas sur une entreprise qui avait adopt\u00e9 la solution de s\u00e9curit\u00e9 g\u00e9r\u00e9e de Present, pour constater d\u00e8s l'installation de nos outils de protection et de surveillance, des activit\u00e9s illicites sur le r\u00e9seau. Un crypto-mineur qui utilise vos ressources informatiques afin de calculer des algorithmes de crypto-monnaie a \u00e9t\u00e9 d\u00e9tect\u00e9 puis \u00e9limin\u00e9 du serveur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.present.ca\/fr\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\/","og_locale":"fr_FR","og_type":"article","og_title":"Un crypto mining squattait les ressources TI d\u2019une entreprise qu\u00e9b\u00e9coise de fabrication - Present","og_description":"\u00c9tude de cas sur une entreprise qui avait adopt\u00e9 la solution de s\u00e9curit\u00e9 g\u00e9r\u00e9e de Present, pour constater d\u00e8s l'installation de nos outils de protection et de surveillance, des activit\u00e9s illicites sur le r\u00e9seau. Un crypto-mineur qui utilise vos ressources informatiques afin de calculer des algorithmes de crypto-monnaie a \u00e9t\u00e9 d\u00e9tect\u00e9 puis \u00e9limin\u00e9 du serveur.","og_url":"https:\/\/www.present.ca\/fr\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\/","og_site_name":"Present","article_modified_time":"2024-01-03T20:44:26+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.present.ca\/wp-content\/uploads\/2022\/05\/Untitled-design-27.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.present.ca\/fr\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\/","url":"https:\/\/www.present.ca\/fr\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\/","name":"Un crypto mining squattait les ressources TI d\u2019une entreprise qu\u00e9b\u00e9coise de fabrication - Present","isPartOf":{"@id":"https:\/\/www.present.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.present.ca\/fr\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\/#primaryimage"},"image":{"@id":"https:\/\/www.present.ca\/fr\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\/#primaryimage"},"thumbnailUrl":"https:\/\/www.present.ca\/wp-content\/uploads\/2022\/05\/Untitled-design-27.png","datePublished":"2022-05-20T00:57:44+00:00","dateModified":"2024-01-03T20:44:26+00:00","description":"\u00c9tude de cas sur une entreprise qui avait adopt\u00e9 la solution de s\u00e9curit\u00e9 g\u00e9r\u00e9e de Present, pour constater d\u00e8s l'installation de nos outils de protection et de surveillance, des activit\u00e9s illicites sur le r\u00e9seau. Un crypto-mineur qui utilise vos ressources informatiques afin de calculer des algorithmes de crypto-monnaie a \u00e9t\u00e9 d\u00e9tect\u00e9 puis \u00e9limin\u00e9 du serveur.","breadcrumb":{"@id":"https:\/\/www.present.ca\/fr\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.present.ca\/fr\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.present.ca\/fr\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\/#primaryimage","url":"https:\/\/www.present.ca\/wp-content\/uploads\/2022\/05\/Untitled-design-27.png","contentUrl":"https:\/\/www.present.ca\/wp-content\/uploads\/2022\/05\/Untitled-design-27.png","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.present.ca\/fr\/un-crypto-mining-squattait-les-ressources-ti-dune-entreprise-quebecoise-de-fabrication\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.present.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Un crypto mining squattait les ressources TI d\u2019une entreprise qu\u00e9b\u00e9coise de fabrication"}]},{"@type":"WebSite","@id":"https:\/\/www.present.ca\/fr\/#website","url":"https:\/\/www.present.ca\/fr\/","name":"Present","description":"Services G\u00e9r\u00e9s TI, S\u00e9curit\u00e9 G\u00e9r\u00e9e TI et Solutions de Cloud Hybride","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.present.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.present.ca\/fr\/wp-json\/wp\/v2\/pages\/23454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.present.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.present.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.present.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.present.ca\/fr\/wp-json\/wp\/v2\/comments?post=23454"}],"version-history":[{"count":4,"href":"https:\/\/www.present.ca\/fr\/wp-json\/wp\/v2\/pages\/23454\/revisions"}],"predecessor-version":[{"id":27840,"href":"https:\/\/www.present.ca\/fr\/wp-json\/wp\/v2\/pages\/23454\/revisions\/27840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.present.ca\/fr\/wp-json\/wp\/v2\/media\/23474"}],"wp:attachment":[{"href":"https:\/\/www.present.ca\/fr\/wp-json\/wp\/v2\/media?parent=23454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}